{"id":6254,"date":"2026-09-01T01:18:32","date_gmt":"2026-09-01T01:18:32","guid":{"rendered":"https:\/\/freedomminds.org\/pt\/caps-para-tratamento-de-alcool-e-drogas-7157673\/"},"modified":"2026-09-01T01:18:33","modified_gmt":"2026-09-01T01:18:33","slug":"caps-para-tratamento-de-alcool-e-drogas-7157673","status":"publish","type":"post","link":"https:\/\/freedomminds.org\/pt\/caps-para-tratamento-de-alcool-e-drogas-7157673\/","title":{"rendered":"CAPS para Tratamento de \u00c1lcool e Drogas &#8211; 7157673"},"content":{"rendered":"<h3>CAPS para Tratamento de \u00c1lcool e Drogas &#8211; 7157673<\/h3>\n<p>Os <strong>CAPS AD (Centros de Aten\u00e7\u00e3o Psicossocial \u00c1lcool e Drogas)<\/strong> s\u00e3o servi\u00e7os p\u00fablicos do SUS especializados no atendimento de pessoas que enfrentam problemas relacionados ao uso de \u00e1lcool e outras drogas. O atendimento pode incluir acompanhamento m\u00e9dico, psicol\u00f3gico, terap\u00eautico, grupos de apoio e orienta\u00e7\u00e3o aos familiares.<\/p>\n<p>7157673<\/p>\n<p>CENTRO DE ATENCAO PSICOSSOCIAL ELOI MENDES MG<\/p>\n<p>ELOI MENDES<\/p>\n<p>A <strong>Freedom Minds<\/strong> incentiva a busca por redes de apoio e acompanhamento adequado no processo de recupera\u00e7\u00e3o. Grupos de ajuda m\u00fatua, como o AA, podem fazer parte de uma rede mais ampla de suporte \u00e0 recupera\u00e7\u00e3o.<\/p>\n<p><strong>Importante:<\/strong> a Freedom Minds n\u00e3o representa nem possui v\u00ednculo institucional com Alco\u00f3licos An\u00f4nimos. As informa\u00e7\u00f5es de endere\u00e7o e hor\u00e1rios devem ser confirmadas diretamente com a organiza\u00e7\u00e3o ou com o grupo mencionado.<\/p>\n<p><a href=\"https:\/\/freedomminds.org\/pt\/curso-online-dependencia-quimica\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" style=\"width: 90%; height: auto; display: block; margin: 0 auto; border-radius: 20px;\" src=\"https:\/\/freedomminds.org\/pt\/wp-content\/uploads\/2026\/08\/ChatGPT-Image-17-de-ago.-de-2026-10_10_50.png\" alt=\"Curso Online Freedom Minds\" width=\"1902\" height=\"827\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAPS para Tratamento de \u00c1lcool e Drogas &#8211; 7157673 Os CAPS AD (Centros de Aten\u00e7\u00e3o&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-6254","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/posts\/6254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/comments?post=6254"}],"version-history":[{"count":0,"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/posts\/6254\/revisions"}],"wp:attachment":[{"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/media?parent=6254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/categories?post=6254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freedomminds.org\/pt\/wp-json\/wp\/v2\/tags?post=6254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}